{"id":23,"count":1,"description":"","link":"https:\/\/construccionesimais.com\/en\/tag\/condensacion-vivienda\/","name":"condensaci\u00f3n vivienda","slug":"condensacion-vivienda","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/construccionesimais.com\/en\/wp-json\/wp\/v2\/tags\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/construccionesimais.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/construccionesimais.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/construccionesimais.com\/en\/wp-json\/wp\/v2\/posts?tags=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}